{"id":12,"count":3,"description":"","link":"https:\/\/kanzlei-bernstorff.de\/en\/category\/weg-recht\/","name":"Condominium Law","slug":"weg-recht","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kanzlei-bernstorff.de\/en\/category\/weg-recht\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kanzlei-bernstorff.de\/en\/category\/weg-recht\/\" \/>\n<meta property=\"og:site_name\" content=\"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/category\\\/weg-recht\\\/\",\"url\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/category\\\/weg-recht\\\/\",\"name\":\"WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/category\\\/weg-recht\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/category\\\/weg-recht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WEG-Recht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#website\",\"url\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/\",\"name\":\"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\",\"description\":\"Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\",\"publisher\":{\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#organization\",\"name\":\"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\",\"url\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/kanzlei-bernstorff-group-x.png\",\"contentUrl\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/kanzlei-bernstorff-group-x.png\",\"width\":1360,\"height\":680,\"caption\":\"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB\"},\"image\":{\"@id\":\"https:\\\/\\\/kanzlei-bernstorff.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kanzlei-bernstorff.de\/en\/category\/weg-recht\/","og_locale":"en_US","og_type":"article","og_title":"WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","og_url":"https:\/\/kanzlei-bernstorff.de\/en\/category\/weg-recht\/","og_site_name":"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kanzlei-bernstorff.de\/category\/weg-recht\/","url":"https:\/\/kanzlei-bernstorff.de\/category\/weg-recht\/","name":"WEG-Recht Archives - Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","isPartOf":{"@id":"https:\/\/kanzlei-bernstorff.de\/#website"},"breadcrumb":{"@id":"https:\/\/kanzlei-bernstorff.de\/category\/weg-recht\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kanzlei-bernstorff.de\/category\/weg-recht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kanzlei-bernstorff.de\/"},{"@type":"ListItem","position":2,"name":"WEG-Recht"}]},{"@type":"WebSite","@id":"https:\/\/kanzlei-bernstorff.de\/#website","url":"https:\/\/kanzlei-bernstorff.de\/","name":"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","description":"Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","publisher":{"@id":"https:\/\/kanzlei-bernstorff.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kanzlei-bernstorff.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/kanzlei-bernstorff.de\/#organization","name":"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB","url":"https:\/\/kanzlei-bernstorff.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kanzlei-bernstorff.de\/#\/schema\/logo\/image\/","url":"https:\/\/kanzlei-bernstorff.de\/wp-content\/uploads\/2025\/12\/kanzlei-bernstorff-group-x.png","contentUrl":"https:\/\/kanzlei-bernstorff.de\/wp-content\/uploads\/2025\/12\/kanzlei-bernstorff-group-x.png","width":1360,"height":680,"caption":"Bernstorff - Rechtsanw\u00e4lte Partnerschaftsgesellschaft mbB"},"image":{"@id":"https:\/\/kanzlei-bernstorff.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kanzlei-bernstorff.de\/en\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kanzlei-bernstorff.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kanzlei-bernstorff.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kanzlei-bernstorff.de\/en\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}